{"id":45972,"date":"2024-05-11T12:53:22","date_gmt":"2024-05-11T12:53:22","guid":{"rendered":"https:\/\/mozaikdesign.com\/?post_type=product&#038;p=45972"},"modified":"2024-05-28T11:55:24","modified_gmt":"2024-05-28T11:55:24","slug":"lever-side-table","status":"publish","type":"product","link":"https:\/\/mozaikdesign.com\/en\/product\/lever-side-table\/","title":{"rendered":"Lever Side Table"},"content":{"rendered":"<h4>The side table series is available in two different sizes.<\/h4>\n<p><strong>Top:<\/strong> stainless steel with glossy varnish (reference colors: Mano Lucida wood sample collection).<br \/>\n<strong>Base:<\/strong> stainless steel bar with glossy varnish (reference colors: Mano Lucida wood sample collection). Plastic spacers.<\/p>\n<p>Notes<br \/>\nThis product can also be used indoors.<\/p>\n<p>We recommend using a Winter Set protection cover.<\/p>\n","protected":false},"excerpt":{"rendered":"<h4>The side table series is available in two different sizes.<\/h4>\n","protected":false},"featured_media":45974,"template":"","meta":{"_acf_changed":false},"product_cat":[1165,1148],"product_tag":[],"class_list":["post-45972","product","type-product","status-publish","has-post-thumbnail","product_cat-coffee-table","product_cat-outdoor-coffee-table","pa_brand-paola-lenti-en","pa_designer-francesco-rota-en","pa_space-garden","pa_space-hotel","pa_space-outdoor","first","onbackorder","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lever Side Table | Mozaik<\/title>\n<meta name=\"description\" content=\"The side table series is available in two different sizes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mozaikdesign.com\/en\/product\/lever-side-table\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lever Side Table | Mozaik\" \/>\n<meta property=\"og:description\" content=\"The side table series is available in two different sizes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mozaikdesign.com\/en\/product\/lever-side-table\/\" \/>\n<meta property=\"og:site_name\" content=\"Mozaik\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/mozaikdesigncom\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-28T11:55:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mozaikdesign.com\/wp-content\/uploads\/2024\/05\/Lever-outdoor-gallery.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mozaik_design\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/product\\\/lever-side-table\\\/\",\"url\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/product\\\/lever-side-table\\\/\",\"name\":\"Lever Side Table | Mozaik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/product\\\/lever-side-table\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/product\\\/lever-side-table\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mozaikdesign.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Lever-outdoor-gallery.jpg\",\"datePublished\":\"2024-05-11T12:53:22+00:00\",\"dateModified\":\"2024-05-28T11:55:24+00:00\",\"description\":\"The side table series is available in two different sizes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/product\\\/lever-side-table\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/product\\\/lever-side-table\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/product\\\/lever-side-table\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mozaikdesign.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Lever-outdoor-gallery.jpg\",\"contentUrl\":\"https:\\\/\\\/mozaikdesign.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Lever-outdoor-gallery.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/product\\\/lever-side-table\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Products\",\"item\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Furniture\",\"item\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/cat\\\/furniture\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Coffee Table\",\"item\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/cat\\\/furniture\\\/coffee-table\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Lever Side Table\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/\",\"name\":\"Mozaik\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/#organization\",\"name\":\"Mozaik\",\"url\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mozaikdesign.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/mozaik-logo-s.jpg\",\"contentUrl\":\"https:\\\/\\\/mozaikdesign.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/mozaik-logo-s.jpg\",\"width\":696,\"height\":696,\"caption\":\"Mozaik\"},\"image\":{\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/mozaikdesigncom\",\"https:\\\/\\\/x.com\\\/mozaik_design\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lever Side Table | Mozaik","description":"The side table series is available in two different sizes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mozaikdesign.com\/en\/product\/lever-side-table\/","og_locale":"en_US","og_type":"article","og_title":"Lever Side Table | Mozaik","og_description":"The side table series is available in two different sizes.","og_url":"https:\/\/mozaikdesign.com\/en\/product\/lever-side-table\/","og_site_name":"Mozaik","article_publisher":"https:\/\/facebook.com\/mozaikdesigncom","article_modified_time":"2024-05-28T11:55:24+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/mozaikdesign.com\/wp-content\/uploads\/2024\/05\/Lever-outdoor-gallery.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@mozaik_design","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mozaikdesign.com\/en\/product\/lever-side-table\/","url":"https:\/\/mozaikdesign.com\/en\/product\/lever-side-table\/","name":"Lever Side Table | Mozaik","isPartOf":{"@id":"https:\/\/mozaikdesign.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mozaikdesign.com\/en\/product\/lever-side-table\/#primaryimage"},"image":{"@id":"https:\/\/mozaikdesign.com\/en\/product\/lever-side-table\/#primaryimage"},"thumbnailUrl":"https:\/\/mozaikdesign.com\/wp-content\/uploads\/2024\/05\/Lever-outdoor-gallery.jpg","datePublished":"2024-05-11T12:53:22+00:00","dateModified":"2024-05-28T11:55:24+00:00","description":"The side table series is available in two different sizes.","breadcrumb":{"@id":"https:\/\/mozaikdesign.com\/en\/product\/lever-side-table\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mozaikdesign.com\/en\/product\/lever-side-table\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mozaikdesign.com\/en\/product\/lever-side-table\/#primaryimage","url":"https:\/\/mozaikdesign.com\/wp-content\/uploads\/2024\/05\/Lever-outdoor-gallery.jpg","contentUrl":"https:\/\/mozaikdesign.com\/wp-content\/uploads\/2024\/05\/Lever-outdoor-gallery.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/mozaikdesign.com\/en\/product\/lever-side-table\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Products","item":"https:\/\/mozaikdesign.com\/en\/products\/"},{"@type":"ListItem","position":2,"name":"Furniture","item":"https:\/\/mozaikdesign.com\/en\/cat\/furniture\/"},{"@type":"ListItem","position":3,"name":"Coffee Table","item":"https:\/\/mozaikdesign.com\/en\/cat\/furniture\/coffee-table\/"},{"@type":"ListItem","position":4,"name":"Lever Side Table"}]},{"@type":"WebSite","@id":"https:\/\/mozaikdesign.com\/en\/#website","url":"https:\/\/mozaikdesign.com\/en\/","name":"Mozaik","description":"","publisher":{"@id":"https:\/\/mozaikdesign.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mozaikdesign.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mozaikdesign.com\/en\/#organization","name":"Mozaik","url":"https:\/\/mozaikdesign.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mozaikdesign.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mozaikdesign.com\/wp-content\/uploads\/2023\/06\/mozaik-logo-s.jpg","contentUrl":"https:\/\/mozaikdesign.com\/wp-content\/uploads\/2023\/06\/mozaik-logo-s.jpg","width":696,"height":696,"caption":"Mozaik"},"image":{"@id":"https:\/\/mozaikdesign.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/mozaikdesigncom","https:\/\/x.com\/mozaik_design"]}]}},"_links":{"self":[{"href":"https:\/\/mozaikdesign.com\/en\/wp-json\/wp\/v2\/product\/45972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mozaikdesign.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mozaikdesign.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mozaikdesign.com\/en\/wp-json\/wp\/v2\/media\/45974"}],"wp:attachment":[{"href":"https:\/\/mozaikdesign.com\/en\/wp-json\/wp\/v2\/media?parent=45972"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mozaikdesign.com\/en\/wp-json\/wp\/v2\/product_cat?post=45972"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mozaikdesign.com\/en\/wp-json\/wp\/v2\/product_tag?post=45972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}