{"id":3282,"count":1,"description":"","link":"https:\/\/mozaikdesign.com\/en\/blog-tag\/venini-en\/","name":"Venini","slug":"venini-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Venini | Mozaik<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mozaikdesign.com\/en\/blog-tag\/venini-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venini | Mozaik\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mozaikdesign.com\/en\/blog-tag\/venini-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Mozaik\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mozaikdesign.com\/wp-content\/uploads\/2025\/02\/mozaik-home-screen-tr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mozaik_design\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/blog-tag\\\/venini-en\\\/\",\"url\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/blog-tag\\\/venini-en\\\/\",\"name\":\"Venini | Mozaik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/\",\"name\":\"Mozaik\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/#organization\",\"name\":\"Mozaik\",\"url\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mozaikdesign.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/mozaik-logo-s.jpg\",\"contentUrl\":\"https:\\\/\\\/mozaikdesign.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/mozaik-logo-s.jpg\",\"width\":696,\"height\":696,\"caption\":\"Mozaik\"},\"image\":{\"@id\":\"https:\\\/\\\/mozaikdesign.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/mozaikdesigncom\",\"https:\\\/\\\/x.com\\\/mozaik_design\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venini | Mozaik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mozaikdesign.com\/en\/blog-tag\/venini-en\/","og_locale":"en_US","og_type":"article","og_title":"Venini | Mozaik","og_url":"https:\/\/mozaikdesign.com\/en\/blog-tag\/venini-en\/","og_site_name":"Mozaik","og_image":[{"width":1200,"height":675,"url":"https:\/\/mozaikdesign.com\/wp-content\/uploads\/2025\/02\/mozaik-home-screen-tr.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@mozaik_design","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mozaikdesign.com\/en\/blog-tag\/venini-en\/","url":"https:\/\/mozaikdesign.com\/en\/blog-tag\/venini-en\/","name":"Venini | Mozaik","isPartOf":{"@id":"https:\/\/mozaikdesign.com\/en\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/mozaikdesign.com\/en\/#website","url":"https:\/\/mozaikdesign.com\/en\/","name":"Mozaik","description":"","publisher":{"@id":"https:\/\/mozaikdesign.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mozaikdesign.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mozaikdesign.com\/en\/#organization","name":"Mozaik","url":"https:\/\/mozaikdesign.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mozaikdesign.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mozaikdesign.com\/wp-content\/uploads\/2023\/06\/mozaik-logo-s.jpg","contentUrl":"https:\/\/mozaikdesign.com\/wp-content\/uploads\/2023\/06\/mozaik-logo-s.jpg","width":696,"height":696,"caption":"Mozaik"},"image":{"@id":"https:\/\/mozaikdesign.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/mozaikdesigncom","https:\/\/x.com\/mozaik_design"]}]}},"_links":{"self":[{"href":"https:\/\/mozaikdesign.com\/en\/wp-json\/wp\/v2\/tags\/3282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mozaikdesign.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mozaikdesign.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mozaikdesign.com\/en\/wp-json\/wp\/v2\/posts?tags=3282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}